{"id":10255,"date":"2023-11-07T11:19:44","date_gmt":"2023-11-07T10:19:44","guid":{"rendered":"https:\/\/associationimperatricezita.com\/vie\/"},"modified":"2025-01-28T16:37:36","modified_gmt":"2025-01-28T15:37:36","slug":"vita","status":"publish","type":"page","link":"https:\/\/associationimperatricezita.com\/it\/vita\/","title":{"rendered":"Vita di Zita, servitore di Dio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10255\" class=\"elementor elementor-10255 elementor-7666\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-278060e e-flex e-con-boxed e-con e-parent\" data-id=\"278060e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a4d041a e-con-full e-flex e-con e-child\" data-id=\"a4d041a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a543ff premium-header-inline premium-lq__none premium-box-lq__none elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"7a543ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-widget-container\">\n\t\t<div class=\"premium-dual-header-wrapper\">\n\t\t\t\t\t<h2 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">Nascita <\/span><span class=\"premium-dual-header-second-header \"> e infanzia <\/span><\/h2> \t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb3250c elementor-widget elementor-widget-text-editor\" data-id=\"bb3250c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zita di Borbone di Parma nacque il 9 maggio 1892 a Villa delle Pianore, in provincia di Lucca, in Toscana, situata tra Pietrasanta e Viareggio, in Italia. Era la diciassettesima figlia di Roberto I di Parma e di sua moglie Maria Antonia di Braganza, figlia del re Michele I, ex re del Portogallo, che perse il trono nel 1834 e si trasfer\u00ec in Austria.<\/p><p>Suo padre Roberto di Parma fu l&#8217;ultimo duca regnante del Ducato di Parma. Ancora minorenne, perse il trono durante i movimenti che lavoravano per l&#8217;unit\u00e0.<\/p><p>Questi eventi segneranno per sempre la sua famiglia.<\/p><p>La famiglia di Roberto di Parma ebbe 24 figli, dodici dei quali nacquero dal suo secondo matrimonio con Maria Antonia del Portogallo. Dal primo letto, tre bambini morirono in tenera et\u00e0 e sei naquero mentalmente disabili. Furono circondati da tutti i loro fratelli e sorelle. La famiglia trascorreva la maggior parte dell&#8217;anno in Bassa Austria al castello di Schwarzau e passava l\u2019inverno a Villa delle Pianore. Zita, come tutti i suoi fratelli, imparo il francese, l&#8217;italiano, il tedesco, lo spagnolo, il portoghese e l&#8217;inglese. Ma suo padre si considerava un principe francese. Era figlio di Luisa di Borbone, sorella del conte di Chambord e nipote del re Carlo X. Per questo motivo il castello di Chambord era la loro luogo di vacanza in Francia.<\/p><p>All&#8217;et\u00e0 di dieci anni, Zita entr\u00f2 in collegio a Zangberg in Baviera, con le Suore della Visitazione. Rimase l\u00ec solo per cinque anni. Suo padre mor\u00ec nel 1907. Nel 1909, come aveva appena fatto la sorella Franzisca, soggiorn\u00f2 presso le monache benedettine di Solesmes che nel 1901 erano dovute andare in esilio dalla Francia e occupavano una vecchia casa trasformata in monastero sull&#8217;isola di Wight.<\/p><p>Tutti i figli del Duca e della Duchessa di Parma furono allevati nella fede cattolica e nell&#8217;attenzione ai pi\u00f9 poveri.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f638726 e-con-full e-flex e-con e-child\" data-id=\"f638726\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9c0f10 elementor-widget elementor-widget-image\" data-id=\"c9c0f10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"478\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-1024x612.jpg\" class=\"attachment-large size-large wp-image-9303\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-1024x612.jpg 1024w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-300x179.jpg 300w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-768x459.jpg 768w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille.jpg 1199w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23649bb e-flex e-con-boxed e-con e-parent\" data-id=\"23649bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5ff6629 e-con-full e-flex e-con e-child\" data-id=\"5ff6629\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d75ff15 elementor-widget elementor-widget-image\" data-id=\"d75ff15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"685\" height=\"1024\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/mariage-zita-8-685x1024.jpg\" class=\"attachment-large size-large wp-image-9307\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/mariage-zita-8-685x1024.jpg 685w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/mariage-zita-8-201x300.jpg 201w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/mariage-zita-8-768x1148.jpg 768w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/mariage-zita-8.jpg 891w\" sizes=\"(max-width: 685px) 100vw, 685px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec5724c e-con-full e-flex e-con e-child\" data-id=\"ec5724c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e235e1b premium-header-inline premium-lq__none premium-box-lq__none elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"e235e1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-widget-container\">\n\t\t<div class=\"premium-dual-header-wrapper\">\n\t\t\t\t\t<h2 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">Matrimonio <\/span><\/h2> \t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1def782 elementor-widget elementor-widget-text-editor\" data-id=\"1def782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante i suoi lunghi soggiorni in Austria durante la sua infanzia, Zita incontr\u00f2 il suo lontano cugino, l&#8217;arciduca Carlo, pronipote dell&#8217;imperatore Francesco Giuseppe. La nonna di Carlo era la zia di Zita. Lei e la sua madre sono sorelle. Gli incontri tra cugini erano numerosi, poi meno frequenti a causa dei loro studi. Si incontrarono di nuovo nel 1909, quando l&#8217;imperatore stava esortando Carlo a sposarsi. Carlo era il secondo in ordine di successione da quando suo zio, l&#8217;arciduca Francesco Ferdinando, aveva contratto un matrimonio morganatico: i suoi figli non potevano reclamare il trono.<\/p><p>Il 13 giugno 1911 si svolse la cerimonia di fidanzamento nella cappella della Villa delle Pianore. Qualche tempo dopo, Zita si rec\u00f2 a Roma con la madre per ricevere la benedizione di Papa Pio X. Era consapevole delle difficolt\u00e0 dell&#8217;impero e delle sfide dell&#8217;unit\u00e0 della monarchia. Carlo e Zita si sposarono il 21 ottobre 1911 al castello di Schwarzau. Il matrimonio fu celebrato dall&#8217;inviato del Papa, il cardinale Bisletti.<\/p><p>Il loro primo figlio, Otto, nacque il 20 novembre 1912. Era il maggiore di otto figli: Ad\u00e9la\u00efde, Robert, F\u00e9lix, Carl-Louis, Rodolphe, Charlotte e la piccola Elisabeth che non conobbe mai suo padre<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62ac006 e-flex e-con-boxed e-con e-parent\" data-id=\"62ac006\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-000bb25 e-con-full e-flex e-con e-child\" data-id=\"000bb25\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a271af premium-header-block premium-lq__none premium-box-lq__none elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"1a271af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-widget-container\">\n\t\t<div class=\"premium-dual-header-wrapper\">\n\t\t\t\t\t<h2 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">Guerra <\/span><span class=\"premium-dual-header-second-header \"> e ascesa al trono <\/span><\/h2> \t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c31904 elementor-widget elementor-widget-text-editor\" data-id=\"3c31904\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Secondo in ordine di successione, Carlo, che ha solo 24 anni, sa che non salir\u00e0 al trono prima di altri vent&#8217;anni. Lui e sua moglie hanno quindi il tempo di prepararsi.<\/p><p>Tutto cambi\u00f2 il 28 giugno 1914, quando l&#8217;arciduca Francesco Ferdinando e sua moglie furono assassinati a Sarajevo dai nazionalisti serbi durante una visita in Bosnia ed Erzegovina. Da subito, si \u00e8 trattato di una spirale in questa parte d&#8217;Europa afflitta da tensioni permanenti. I sostenitori della guerra si oppongono a coloro che desiderano fare tutto il possibile per preservare la pace. Tuttavia, Carlo fu tenuto fuori dalle decisioni.<\/p><p>Da agosto, l&#8217;Europa entr\u00f2 in guerra. L&#8217;arciduca Carlo divenne generale dell&#8217;esercito austriaco e fu mandato in Tirolo. Zita e i suoi figli si trasferirono nel Castello di Sch\u00f6nbrunn. Zita passava parte delle sue giornate negli ospedali di Vienna. A volte accompagnava il marito al fronte, soprattutto sul fronte rumeno, dove passava ore con i feriti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5efa98 elementor-widget elementor-widget-image\" data-id=\"e5efa98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"693\" height=\"1024\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/trone-693x1024.jpg\" class=\"attachment-large size-large wp-image-9315\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/trone-693x1024.jpg 693w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/trone-203x300.jpg 203w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/trone-768x1135.jpg 768w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/trone-1040x1536.jpg 1040w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/trone.jpg 1280w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44b0c32 elementor-widget elementor-widget-text-editor\" data-id=\"44b0c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alla fine, i tentativi di pace fallirono. Da quel momento in poi, l&#8217;intero impero austro-ungarico croll\u00f2 con la dichiarazione di indipendenza di ciascuna delle sue componenti.<\/p><p>Fu proclamata la nuova Repubblica Tedesca d&#8217;Austria e all&#8217;imperatore fu chiesto di ritirarsi da tutti i suoi poteri, ma egli non abdic\u00f2 mai. Con i loro figli, Charles e Zita si stabilirono a Eckartsau. Inizia cos\u00ec una vita di vagabondaggio ed esilio che li porter\u00e0 in Svizzera nel marzo del 1919. Due tentativi di restaurazione in Ungheria si conclusero con un fallimento, nel marzo e nell&#8217;ottobre 1921. Quest&#8217;ultimo tentativo li port\u00f2 a un esilio ancora pi\u00f9 lontano dal loro impero: a Funchal, sull&#8217;isola di Madeira.<\/p><p>Abbandonati da tutti, vivranno nella povert\u00e0 e nel disagio, non avendo mezzi finanziari nemmeno quando Carlo si ammaler\u00e0. Esausto, ma completamente abbandonato alla volont\u00e0 di Dio, mor\u00ec all&#8217;et\u00e0 di 34 anni, sabato 1\u00b0 aprile 1922, offrendo la sua vita per la riconciliazione dei suoi popoli.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff01512 e-con-full e-flex e-con e-child\" data-id=\"ff01512\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7e79ee elementor-widget elementor-widget-image\" data-id=\"a7e79ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"1024\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/assassinat-693x1024.jpg\" class=\"attachment-large size-large wp-image-9311\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/assassinat-693x1024.jpg 693w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/assassinat-203x300.jpg 203w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/assassinat-768x1134.jpg 768w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/assassinat-1040x1536.jpg 1040w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/assassinat.jpg 1200w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee30376 elementor-widget elementor-widget-text-editor\" data-id=\"ee30376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questa guerra fu particolarmente crudele per lei: i suoi fratelli, i principi Felice e Renato si erano arruolati nell&#8217;esercito austriaco, mentre i principi Sisto e Saverio si erano arruolati nell&#8217;esercito belga (perch\u00e9 non erano in grado di farlo nell&#8217;esercito francese).<\/p><p>Per due anni, Zita divise il suo tempo tra i figli e gli ospedali, pur rimanendo al fianco del vecchio imperatore. Fran\u00e7ois Joseph mor\u00ec il 21 novembre 1916, all&#8217;et\u00e0 di 86 anni. Secondo la Prammatica Sanzione, Carlo fu proclamato Imperatore d&#8217;Austria, Re d&#8217;Ungheria, Re di Boemia, Re di Croazia, ecc.<\/p><p>Cos\u00ec inizi\u00f2 per i giovani monarchi una vita di dolore e sofferenza in una situazione che non avevano scelto. Intuendo che l&#8217;Ungheria poteva separarsi, quando aveva bisogno di tutte le sue forze armate, Carlo stesso si fece incoronare re d&#8217;Ungheria il 30 dicembre 1916. Sar\u00e0 l&#8217;unico momento di gloria nella vita degli sposi, ma una gloria che molto presto divenne un abbandono alla volont\u00e0 divina. I festeggiamenti furono di breve durata, poich\u00e9 il nuovo re deve partire per visitare il fronte.<\/p><p>Sempre al fianco del marito, l&#8217;imperatrice Zita lo assisteva. Lo accompagn\u00f2 nelle varie province e al fronte, continu\u00f2 le sue opere di carit\u00e0 e and\u00f2 a vedere i feriti di guerra. \u00c8 particolarmente interessata agli affari sociali. Inoltre, durante la sua breve vita come imperatore, Carlo fu il primo capo di stato a creare un Ministero degli Affari Sociali. Non smise mai di cercare la pace e anche una pace separata con la Francia e l&#8217;Inghilterra, attraverso i fratelli di Zita, i principi Sisto e Saverio di Borbone di Parma. Il piano di pace era lungo e difficile: l&#8217;Austria-Ungheria era legata alla Germania, che voleva continuare la guerra, mentre la Russia stava crollando, i generali inglesi erano restii a fare la pace con l&#8217;Austria e la Francia parlava a pi\u00f9 voci. Il papa Benedetto XV invoc\u00f2 i belligeranti alla pace: solo l&#8217;imperatore Carlo rispose positivamente. Nel frattempo, l&#8217;imperatrice Zita ottenne dai tedeschi la promessa di risparmiare la popolazione civile, di non bombardare la casa del re e della regina del Belgio e di preservare la cattedrale di Reims.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-898bd18 elementor-widget elementor-widget-image\" data-id=\"898bd18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"449\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/12\/exil-3.jpg\" class=\"attachment-large size-large wp-image-9829\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/12\/exil-3.jpg 687w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/12\/exil-3-300x196.jpg 300w\" sizes=\"(max-width: 687px) 100vw, 687px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcd7752 e-flex e-con-boxed e-con e-parent\" data-id=\"fcd7752\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9cec817 e-con-full e-flex e-con e-child\" data-id=\"9cec817\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20ffca8 elementor-widget elementor-widget-image\" data-id=\"20ffca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"503\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-veuve-et-ses-enfants-1024x644.jpg\" class=\"attachment-large size-large wp-image-9322\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-veuve-et-ses-enfants-1024x644.jpg 1024w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-veuve-et-ses-enfants-300x189.jpg 300w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-veuve-et-ses-enfants-768x483.jpg 768w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-veuve-et-ses-enfants-1320x831.jpg 1320w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-veuve-et-ses-enfants.jpg 1381w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-487eafe elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"487eafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"793\" height=\"419\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/IMG_0059.jpg\" class=\"attachment-large size-large wp-image-9323\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/IMG_0059.jpg 793w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/IMG_0059-300x159.jpg 300w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/IMG_0059-768x406.jpg 768w\" sizes=\"(max-width: 793px) 100vw, 793px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e2f7ec e-con-full e-flex e-con e-child\" data-id=\"0e2f7ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86224b8 premium-header-block premium-bg-text-yes premium-lq__none premium-box-lq__none elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"86224b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-widget-container\">\n\t\t<div class=\"premium-dual-header-wrapper\">\n\t\t\t\t\t<h2 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">Vedovanza <\/span><span class=\"premium-dual-header-second-header \">e nuovo esilio <\/span><\/h2> \t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e872b4c elementor-widget elementor-widget-text-editor\" data-id=\"e872b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;imperatrice Zita rimase vedova all&#8217;et\u00e0 di 30 anni. Ebbe 7 figli, l&#8217;ottavo, la piccola arciduchessa Elisabetta, nacque due mesi dopo. Zita portava tutta la sua vita il lutto per lealt\u00e0 al suo amato marito.<\/p><p>La Conferenza degli Ambasciatori, grazie all&#8217;intervento del Re Alfonso XIII di Spagna, la autorizz\u00f2 a stabilirsi in Spagna, a Lequeitio, nel Paese Bascho, dove rimase per 6 anni per dedicarsi all&#8217;educazione dei suoi figli. Poi, consapevole di doversi preparare per il loro futuro, nel 1929 si trasfer\u00ec a Steenokkerzeel, vicino a Bruxelles, in modo che i suoi figli maggiori potessero studiare all&#8217;Universit\u00e0 di Lovanio. Zita si tiene in contatto con i suoi fedeli sudditi e accoglie molti di loro in Belgio. Ma nel 1938, quando l&#8217;Austria fu annessa al regime nazista, la repressione cadde su coloro che rimasero legati alla famiglia imperiale. Nel maggio 1940, l&#8217;imperatrice Zita and\u00f2 nuovamente in esilio dopo l&#8217;invasione del Belgio da parte delle truppe tedesche.<\/p><p>Dopo aver attraversato la Francia, poi la Spagna e il Portogallo, la famiglia si stabil\u00ec definitivamente in Quebec, una provincia francofona. La povert\u00e0 fu una realt\u00e0 quotidiana per tutto questo periodo, il che non imped\u00ec all&#8217;imperatrice, alla fine della guerra, di tenere conferenze negli Stati Uniti e in Canada per raccogliere fondi per aiutare l&#8217;Austria e l&#8217;Ungheria devastate dalla guerra. Suo figlio Otto impieg\u00f2 tutte le sue energie per far s\u00ec che l&#8217;Austria fosse riconosciuta come paese occupato dal regime nazista e potesse riconquistare la sua indipendenza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7fcac5 e-flex e-con-boxed e-con e-parent\" data-id=\"c7fcac5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d134693 e-con-full e-flex e-con e-child\" data-id=\"d134693\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6535e8e premium-header-block premium-bg-text-yes premium-lq__none premium-box-lq__none elementor-widget elementor-widget-premium-addon-dual-header\" data-id=\"6535e8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-dual-header.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-widget-container\">\n\t\t<div class=\"premium-dual-header-wrapper\">\n\t\t\t\t\t<h2 class=\"premium-dual-header-first-header \"><span class=\"premium-dual-header-first-span\">Ritorno <\/span><span class=\"premium-dual-header-second-header \">in Europa <\/span><\/h2> \t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2726672 elementor-widget elementor-widget-text-editor\" data-id=\"2726672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nel 1953, quando i suoi figli si erano tutti indipendenti e molti di loro sposati, Zita decise di tornare in Europa per prendersi cura di sua madre Maria-Antonia, che mor\u00ec all&#8217;et\u00e0 di 96 anni. Poi si \u00e8 trasferita a Zizers, in Svizzera, nel cantone dei Grigioni. Faceva lunghi soggiorni annuali con le monache benedettine di Solesmes, che conosceva bene: tre delle sue sorelle erano monache a Sainte-C\u00e9cile e lei era Oblata di Saint-Pierre dal 1926. Divideva il suo tempo tra i figli e i nipoti, i suoi fedeli che spesso venivano a trovarla e a chiederle consigli, e il monastero di Solesmes.<\/p><p>Pot\u00e9 finalmente tornare in Austria nel 1982, quando le autorit\u00e0 austriache decisero finalmente che l&#8217;imperatrice come moglie non era interessata dalle leggi sull&#8217;esilio che colpivano gli Asburgo. Ha 90 anni. \u00c8 un trionfo!<\/p><p>Sebbene la sua salute fosse stata a lungo solida, inizi\u00f2 a declinare. Ha gradualmente perso l&#8217;uso della vista e i suoi ultimi mesi furono stati particolarmente dolorosi a causa della polmonite. Ebbe potuto rivedere i suoi figli prima di morire il 14 marzo 1989, all&#8217;et\u00e0 di 96 anni.<\/p><p>Il funerale fu grandioso. L&#8217;imperatrice \u00e8 sepolta nella cripta dei Cappuccini, il suo cuore \u00e8 custodito nel monastero di Muri, in Svizzera, accanto a quello del marito.<\/p><p>Il marito di Zita, Carlo I d&#8217;Austria, fu stato beatificato a Roma il 3 ottobre 2004 da papa Giovanni Paolo II.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf6b0fc e-con-full e-flex e-con e-child\" data-id=\"bf6b0fc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3afc40 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"c3afc40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"534\" src=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/10\/venerable-zita-de-bourbon-parme.jpg\" class=\"attachment-large size-large wp-image-4652\" alt=\"\" srcset=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/10\/venerable-zita-de-bourbon-parme.jpg 375w, https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/10\/venerable-zita-de-bourbon-parme-211x300.jpg 211w\" sizes=\"(max-width: 375px) 100vw, 375px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nascita e infanzia Zita di Borbone di Parma nacque il 9 maggio 1892 a Villa delle Pianore, in provincia di Lucca, in Toscana, situata tra Pietrasanta e Viareggio, in Italia. Era la diciassettesima figlia di Roberto I di Parma e di sua moglie Maria Antonia di Braganza, figlia del re Michele I, ex re del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-10255","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vita di Zita, servitore di Dio - Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita<\/title>\n<meta name=\"description\" content=\"Zita de Bourbon Parme na\u00eet le 9 mai 1892 \u00e0 la Villa delle Pianore, dans la province de Lucques, en Toscane. Elle est la dix-septi\u00e8me enfant de Robert Ier de Parme et Maria-Antonia de Bragance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/associationimperatricezita.com\/it\/vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vita di Zita, servitore di Dio - Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita\" \/>\n<meta property=\"og:description\" content=\"Zita de Bourbon Parme na\u00eet le 9 mai 1892 \u00e0 la Villa delle Pianore, dans la province de Lucques, en Toscane. Elle est la dix-septi\u00e8me enfant de Robert Ier de Parme et Maria-Antonia de Bragance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/associationimperatricezita.com\/it\/vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BeatificaZita\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T15:37:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1199\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/\",\"url\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/\",\"name\":\"Vita di Zita, servitore di Dio - Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/associationimperatricezita.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zita-et-sa-famille-1024x612.jpg\",\"datePublished\":\"2023-11-07T10:19:44+00:00\",\"dateModified\":\"2025-01-28T15:37:36+00:00\",\"description\":\"Zita de Bourbon Parme na\u00eet le 9 mai 1892 \u00e0 la Villa delle Pianore, dans la province de Lucques, en Toscane. Elle est la dix-septi\u00e8me enfant de Robert Ier de Parme et Maria-Antonia de Bragance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/associationimperatricezita.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zita-et-sa-famille-1024x612.jpg\",\"contentUrl\":\"https:\\\/\\\/associationimperatricezita.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zita-et-sa-famille-1024x612.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vita di Zita, servitore di Dio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/\",\"name\":\"Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/#organization\",\"name\":\"Association pour la b\u00e9atification de l'Imp\u00e9ratrice Zita\",\"url\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/associationimperatricezita.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/ABIZ-LOGO-couleurs-BD.jpg\",\"contentUrl\":\"https:\\\/\\\/associationimperatricezita.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/ABIZ-LOGO-couleurs-BD.jpg\",\"width\":1000,\"height\":727,\"caption\":\"Association pour la b\u00e9atification de l'Imp\u00e9ratrice Zita\"},\"image\":{\"@id\":\"https:\\\/\\\/associationimperatricezita.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BeatificaZita\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vita di Zita, servitore di Dio - Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita","description":"Zita de Bourbon Parme na\u00eet le 9 mai 1892 \u00e0 la Villa delle Pianore, dans la province de Lucques, en Toscane. Elle est la dix-septi\u00e8me enfant de Robert Ier de Parme et Maria-Antonia de Bragance.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/associationimperatricezita.com\/it\/vita\/","og_locale":"it_IT","og_type":"article","og_title":"Vita di Zita, servitore di Dio - Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita","og_description":"Zita de Bourbon Parme na\u00eet le 9 mai 1892 \u00e0 la Villa delle Pianore, dans la province de Lucques, en Toscane. Elle est la dix-septi\u00e8me enfant de Robert Ier de Parme et Maria-Antonia de Bragance.","og_url":"https:\/\/associationimperatricezita.com\/it\/vita\/","og_site_name":"Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita","article_publisher":"https:\/\/www.facebook.com\/BeatificaZita\/","article_modified_time":"2025-01-28T15:37:36+00:00","og_image":[{"width":1199,"height":717,"url":"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/associationimperatricezita.com\/it\/vita\/","url":"https:\/\/associationimperatricezita.com\/it\/vita\/","name":"Vita di Zita, servitore di Dio - Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita","isPartOf":{"@id":"https:\/\/associationimperatricezita.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/associationimperatricezita.com\/it\/vita\/#primaryimage"},"image":{"@id":"https:\/\/associationimperatricezita.com\/it\/vita\/#primaryimage"},"thumbnailUrl":"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-1024x612.jpg","datePublished":"2023-11-07T10:19:44+00:00","dateModified":"2025-01-28T15:37:36+00:00","description":"Zita de Bourbon Parme na\u00eet le 9 mai 1892 \u00e0 la Villa delle Pianore, dans la province de Lucques, en Toscane. Elle est la dix-septi\u00e8me enfant de Robert Ier de Parme et Maria-Antonia de Bragance.","breadcrumb":{"@id":"https:\/\/associationimperatricezita.com\/it\/vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/associationimperatricezita.com\/it\/vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/associationimperatricezita.com\/it\/vita\/#primaryimage","url":"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-1024x612.jpg","contentUrl":"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/11\/zita-et-sa-famille-1024x612.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/associationimperatricezita.com\/it\/vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/associationimperatricezita.com\/it\/"},{"@type":"ListItem","position":2,"name":"Vita di Zita, servitore di Dio"}]},{"@type":"WebSite","@id":"https:\/\/associationimperatricezita.com\/it\/#website","url":"https:\/\/associationimperatricezita.com\/it\/","name":"Association pour la b\u00e9atification de l&#039;Imp\u00e9ratrice Zita","description":"","publisher":{"@id":"https:\/\/associationimperatricezita.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/associationimperatricezita.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/associationimperatricezita.com\/it\/#organization","name":"Association pour la b\u00e9atification de l'Imp\u00e9ratrice Zita","url":"https:\/\/associationimperatricezita.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/associationimperatricezita.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/09\/ABIZ-LOGO-couleurs-BD.jpg","contentUrl":"https:\/\/associationimperatricezita.com\/wp-content\/uploads\/2023\/09\/ABIZ-LOGO-couleurs-BD.jpg","width":1000,"height":727,"caption":"Association pour la b\u00e9atification de l'Imp\u00e9ratrice Zita"},"image":{"@id":"https:\/\/associationimperatricezita.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BeatificaZita\/"]}]}},"_links":{"self":[{"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/pages\/10255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/comments?post=10255"}],"version-history":[{"count":5,"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/pages\/10255\/revisions"}],"predecessor-version":[{"id":10675,"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/pages\/10255\/revisions\/10675"}],"wp:attachment":[{"href":"https:\/\/associationimperatricezita.com\/it\/wp-json\/wp\/v2\/media?parent=10255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}